{"id":59059,"date":"2026-05-02T12:05:00","date_gmt":"2026-05-02T17:05:00","guid":{"rendered":"https:\/\/elregionaldetamaulipas.com.mx\/?p=59059"},"modified":"2026-05-05T23:05:50","modified_gmt":"2026-05-06T04:05:50","slug":"fortalece-la-uat-cultura-de-inclusion-desde-la-primera-infancia","status":"publish","type":"post","link":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/2026\/05\/02\/fortalece-la-uat-cultura-de-inclusion-desde-la-primera-infancia\/","title":{"rendered":"Fortalece la UAT cultura de inclusi\u00f3n desde la primera infancia"},"content":{"rendered":"\n<p>Ciudad Victoria, Tamaulipas. &#8211; La Universidad Aut\u00f3noma de Tamaulipas reafirma su compromiso con una educaci\u00f3n humanista, inclusiva y con sentido social, mediante acciones impulsadas por Familia UAT a trav\u00e9s del Centro de Desarrollo Infantil (CENDI UAT), fortaleciendo la atenci\u00f3n integral de ni\u00f1as y ni\u00f1os, as\u00ed como el acompa\u00f1amiento a madres y padres de familia en temas fundamentales para el desarrollo de la infancia.<\/p>\n\n\n\n<p>Como parte de esta visi\u00f3n institucional, se realiz\u00f3 la pl\u00e1tica \u201cComprender para acompa\u00f1ar. Encuentro entre padres\u201d, en un espacio de reflexi\u00f3n sobre educaci\u00f3n especial e inclusiva que reuni\u00f3 a especialistas, familias y comunidad educativa para dialogar sobre la atenci\u00f3n y acompa\u00f1amiento a ni\u00f1as y ni\u00f1os neurodivergentes.<\/p>\n\n\n\n<p>Esta actividad refleja el impulso que desde la administraci\u00f3n del rector D\u00e1maso Anaya Alvarado se ha dado a una educaci\u00f3n en donde la inclusi\u00f3n se asume como una pr\u00e1ctica cotidiana que fortalece la formaci\u00f3n integral desde las primeras etapas de vida.<\/p>\n\n\n\n<p>Durante el encuentro, se destac\u00f3 el trabajo que realiza el Departamento de Desarrollo Infantil del CENDI UAT, en Ciudad Victoria, y que ha sido creado con el respaldo de Familia UAT, encabezada por su presidenta, Isolda Rend\u00f3n de Anaya, consolidando un espacio pionero de acompa\u00f1amiento para ni\u00f1as y ni\u00f1os que requieren atenci\u00f3n especializada dentro de un entorno escolar incluyente.<\/p>\n\n\n\n<p>La directora del CENDI UAT, Ver\u00f3nica Raquel Garza L\u00f3pez, destac\u00f3 que este modelo articula esfuerzos entre familias, especialistas y escuela para brindar acompa\u00f1amiento oportuno a estudiantes neurodivergentes, favoreciendo una atenci\u00f3n integral e incluyente.<\/p>\n\n\n\n<p>Explic\u00f3 que el centro impulsa acciones de canalizaci\u00f3n profesional, detecci\u00f3n temprana y seguimiento conjunto con terapeutas y padres de familia, fortaleciendo una din\u00e1mica de corresponsabilidad que genera mejores resultados y consolida a este centro de ense\u00f1anza y desarrollo infantil como referente en pr\u00e1cticas educativas inclusivas.<\/p>\n\n\n\n<p>La jornada cont\u00f3 con la participaci\u00f3n de la asociaci\u00f3n civil Autismo a Color, que comparti\u00f3 herramientas de orientaci\u00f3n para madres y padres sobre comprensi\u00f3n del espectro autista, diagn\u00f3stico oportuno, acompa\u00f1amiento familiar y construcci\u00f3n de redes de apoyo, resaltando que la informaci\u00f3n, la empat\u00eda y la comunidad son pilares esenciales en estos procesos.&nbsp;<\/p>\n\n\n\n<p>En este espacio de escucha y construcci\u00f3n colectiva, madres y padres de familia compartieron testimonios sobre el acompa\u00f1amiento brindado por el CENDI UAT, destacando el papel de las maestras y del personal especializado en la generaci\u00f3n de ambientes seguros, sensibles e incluyentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad Victoria, Tamaulipas. &#8211; La Universidad Aut\u00f3noma de Tamaulipas reafirma su compromiso con una educaci\u00f3n humanista, inclusiva y con sentido social, mediante acciones impulsadas por Familia UAT a trav\u00e9s del Centro de Desarrollo Infantil (CENDI UAT), fortaleciendo la atenci\u00f3n integral de ni\u00f1as y ni\u00f1os, as\u00ed como el acompa\u00f1amiento a madres y padres de familia en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59060,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,13,16,14,17,7],"tags":[],"class_list":["post-59059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacada","category-destacadas","category-portada","category-portadas","category-universidad","category-uat"],"_links":{"self":[{"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59059"}],"version-history":[{"count":1,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59059\/revisions"}],"predecessor-version":[{"id":59061,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59059\/revisions\/59061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59060"}],"wp:attachment":[{"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elregionaldetamaulipas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}